{"id":256,"date":"2020-09-02T15:30:00","date_gmt":"2020-09-02T18:30:00","guid":{"rendered":"https:\/\/www.bebechegou.com\/blog\/?p=256"},"modified":"2020-09-02T05:48:41","modified_gmt":"2020-09-02T08:48:41","slug":"consumo-de-probioticos-na-gestacao","status":"publish","type":"post","link":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/","title":{"rendered":"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9-1024x1024.png\" alt=\"\" class=\"wp-image-257 lazyload\" data-srcset=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9-1024x1024.png 1024w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9-300x300.png 300w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9-150x150.png 150w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9-768x768.png 768w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9-270x270.png 270w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9.png 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><\/figure>\n\n\n\n<p>Os probi\u00f3ticos s\u00e3o microrganismos vivos que recomp\u00f5em de forma positiva a flora intestinal. Eles t\u00eam a capacidade de atravessar o tubo digestivo e, no intestino grosso, reduzem a multiplica\u00e7\u00e3o de bact\u00e9rias que provocam doen\u00e7as, protegendo o indiv\u00edduo. S\u00e3o essenciais para todas as pessoas, mas t\u00eam papel ainda mais importante durante a&nbsp;gesta\u00e7\u00e3o.<\/p>\n\n\n\n<p>Quando consumidos, ajudam a manter um equil\u00edbrio apropriado entre os bilh\u00f5es de bact\u00e9rias boas e ruins no c\u00f3lon. Tamb\u00e9m nos referimos aos probi\u00f3ticos como \u201cbact\u00e9rias do bem\u201d, porque mant\u00eam o sistema digestivo saud\u00e1vel e impedem que bact\u00e9rias ruins ou nocivas se reproduzam. <\/p>\n\n\n\n<p>Os prebi\u00f3ticos, por outro lado, s\u00e3o componentes alimentares que n\u00e3o digerimos e que alimentam probi\u00f3ticos e boas bact\u00e9rias para que possam crescer. Probi\u00f3ticos e prebi\u00f3ticos podem ser ingeridos naturalmente ou por meio de suplementos. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Os benef\u00edcios<\/h2>\n\n\n\n<p>Os probi\u00f3ticos mais comuns s\u00e3o os lactobacilos e as bifidobact\u00e9rias. Eles atuam no processo de digest\u00e3o dos alimentos e ajudam na absor\u00e7\u00e3o dos nutrientes. Al\u00e9m disso, s\u00e3o aliados no controle do colesterol e na estimula\u00e7\u00e3o das c\u00e9lulas do sistema imune. Entre os v\u00e1rios benef\u00edcios do uso de probi\u00f3ticos na&nbsp;gravidez&nbsp;est\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Aux\u00edlio na regulariza\u00e7\u00e3o do tr\u00e2nsito intestinal, prevenindo constipa\u00e7\u00f5es;<\/li><li>Redu\u00e7\u00e3o da forma\u00e7\u00e3o de gases;<\/li><li>Prote\u00e7\u00e3o do intestino;<\/li><li>Fortalecimento do sistema imunol\u00f3gico. <\/li><li>Combate enfermidades como gripes e infec\u00e7\u00f5es diversas;<\/li><li>Traz sensa\u00e7\u00e3o de bem-estar;<\/li><li>Maior disposi\u00e7\u00e3o;<\/li><li>Menor irritabilidade;<\/li><li>Equil\u00edbrio do humor;<\/li><li>Redu\u00e7\u00e3o das chances de depress\u00e3o;<\/li><\/ul>\n\n\n\n<p>Ao ajudar na lenta absor\u00e7\u00e3o dos nutrientes presentes nos&nbsp;carboidratos, os probi\u00f3ticos auxiliam, ainda, no controle do peso e na redu\u00e7\u00e3o das chances de as mam\u00e3es desenvolverem diabetes gestacional. Eles tamb\u00e9m diminuem o risco de pr\u00e9-ecl\u00e2mpsia e, depois do&nbsp;parto, auxiliam no retorno mais r\u00e1pido ao peso&nbsp;pr\u00e9-gestacional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Probi\u00f3ticos na Alimenta\u00e7\u00e3o<\/h2>\n\n\n\n<p>Pesquisas mostram que os probi\u00f3ticos reduzem as chances de o beb\u00ea nascer com sobrepeso ou de ter&nbsp;obesidade&nbsp;na fase adulta. Outros estudos associam o consumo a uma maior prote\u00e7\u00e3o intestinal, diminuindo a probabilidade de a&nbsp;crian\u00e7a&nbsp;desenvolver alergias alimentares. <\/p>\n\n\n\n<p>Os probi\u00f3ticos est\u00e3o presentes nos seguintes alimentos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Kefir<\/li><li>Coalhada<\/li><li>Leite fermentado<\/li><li>Chucrute<\/li><li>Miss\u00f4<\/li><li>Molho de soja<\/li><li>Kombucha<\/li><li>Iogurtes brancos<\/li><\/ul>\n\n\n\n<p>Em forma de&nbsp;suplementos, eles podem ser encontrados nas vers\u00f5es em sach\u00eas ou c\u00e1psulas. Converse com sua nutricionista para que ela esclare\u00e7a sobre a necessidade de voc\u00ea consumir ou n\u00e3o os probi\u00f3ticos e qual seria o mais recomendado para voc\u00ea.<\/p>\n\n\n\n<p>Texto por Ana Caroline Setti \u2013 Nutricionista Materno Infantil<br>\nCRN 8-12764<br>\n@carolsettinutri<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os probi\u00f3ticos s\u00e3o microrganismos vivos que recomp\u00f5em de forma positiva a flora intestinal. Eles t\u00eam a capacidade de atravessar o tubo digestivo e, no intestino grosso, reduzem a multiplica\u00e7\u00e3o de bact\u00e9rias que provocam doen\u00e7as, protegendo o indiv\u00edduo. S\u00e3o essenciais para todas as pessoas, mas t\u00eam papel ainda mais importante durante a&nbsp;gesta\u00e7\u00e3o. Quando consumidos, ajudam a &hellip; <\/p>\n<p class=\"read-more\"><a class=\"readmore-btn\" href=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/\">+<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":257,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[157,18,84,117,58,19,36,156,126,158,43,32,75,68,153,151],"class_list":["post-256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuidados-na-gravidez-cuidados-na-gravidez","tag-alimentacao-na-gravidez","tag-alimentacao-saudavel","tag-estou-gravida","tag-familia","tag-futura-mamae","tag-gestacao","tag-gestantes","tag-gravida-saudavel","tag-gravidas-2020","tag-gravidas-2021","tag-gravidez-saudavel","tag-maes-de-primeira-viagem","tag-maternidade","tag-nutricao","tag-nutricao-gestacional","tag-probiotico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o - Blog - bebechegou.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o - Blog - bebechegou.com\" \/>\n<meta property=\"og:description\" content=\"Os probi\u00f3ticos s\u00e3o microrganismos vivos que recomp\u00f5em de forma positiva a flora intestinal. Eles t\u00eam a capacidade de atravessar o tubo digestivo e, no intestino grosso, reduzem a multiplica\u00e7\u00e3o de bact\u00e9rias que provocam doen\u00e7as, protegendo o indiv\u00edduo. S\u00e3o essenciais para todas as pessoas, mas t\u00eam papel ainda mais importante durante a&nbsp;gesta\u00e7\u00e3o. Quando consumidos, ajudam a &hellip; + Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - bebechegou.com\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com.br\/bebechegou1\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-02T18:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9-768x768.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"bebechegou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bebechegou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/\"},\"author\":{\"name\":\"bebechegou\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/person\\\/359cfe12ff86958446433b00d3dd6f9c\"},\"headline\":\"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o\",\"datePublished\":\"2020-09-02T18:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/\"},\"wordCount\":481,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/C\u00f3pia-de-e-chegou-feed-9.png\",\"keywords\":[\"alimentacao na gravidez\",\"alimenta\u00e7\u00e3o saud\u00e1vel\",\"estou gravida\",\"familia\",\"futura mamae\",\"gesta\u00e7\u00e3o\",\"gestantes\",\"gravida saudavel\",\"gravidas 2020\",\"gravidas 2021\",\"gravidez saud\u00e1vel\",\"m\u00e3es de primeira viagem\",\"maternidade\",\"nutri\u00e7\u00e3o\",\"nutricao gestacional\",\"probiotico\"],\"articleSection\":[\"Cuidados na Gravidez\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/\",\"name\":\"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o - Blog - bebechegou.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/C\u00f3pia-de-e-chegou-feed-9.png\",\"datePublished\":\"2020-09-02T18:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/C\u00f3pia-de-e-chegou-feed-9.png\",\"contentUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/C\u00f3pia-de-e-chegou-feed-9.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/09\\\/02\\\/consumo-de-probioticos-na-gestacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\",\"name\":\"bebechegou.com - Ch\u00e1 de beb\u00ea Online, Ch\u00e1 de Fraldas Online\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\",\"name\":\"beb\u00ea chegou\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_bebe215.png\",\"contentUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_bebe215.png\",\"width\":215,\"height\":49,\"caption\":\"beb\u00ea chegou\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com.br\\\/bebechegou1\",\"http:\\\/\\\/instagram.com\\\/bebechegouoficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/person\\\/359cfe12ff86958446433b00d3dd6f9c\",\"name\":\"bebechegou\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o - Blog - bebechegou.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o - Blog - bebechegou.com","og_description":"Os probi\u00f3ticos s\u00e3o microrganismos vivos que recomp\u00f5em de forma positiva a flora intestinal. Eles t\u00eam a capacidade de atravessar o tubo digestivo e, no intestino grosso, reduzem a multiplica\u00e7\u00e3o de bact\u00e9rias que provocam doen\u00e7as, protegendo o indiv\u00edduo. S\u00e3o essenciais para todas as pessoas, mas t\u00eam papel ainda mais importante durante a&nbsp;gesta\u00e7\u00e3o. Quando consumidos, ajudam a &hellip; + Read More","og_url":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/","og_site_name":"Blog - bebechegou.com","article_publisher":"http:\/\/facebook.com.br\/bebechegou1","article_published_time":"2020-09-02T18:30:00+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9-768x768.png","type":"image\/png"}],"author":"bebechegou","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"bebechegou","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/#article","isPartOf":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/"},"author":{"name":"bebechegou","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/person\/359cfe12ff86958446433b00d3dd6f9c"},"headline":"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o","datePublished":"2020-09-02T18:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/"},"wordCount":481,"publisher":{"@id":"https:\/\/www.bebechegou.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9.png","keywords":["alimentacao na gravidez","alimenta\u00e7\u00e3o saud\u00e1vel","estou gravida","familia","futura mamae","gesta\u00e7\u00e3o","gestantes","gravida saudavel","gravidas 2020","gravidas 2021","gravidez saud\u00e1vel","m\u00e3es de primeira viagem","maternidade","nutri\u00e7\u00e3o","nutricao gestacional","probiotico"],"articleSection":["Cuidados na Gravidez"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/","url":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/","name":"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o - Blog - bebechegou.com","isPartOf":{"@id":"https:\/\/www.bebechegou.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/#primaryimage"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9.png","datePublished":"2020-09-02T18:30:00+00:00","breadcrumb":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/#primaryimage","url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9.png","contentUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/09\/C\u00f3pia-de-e-chegou-feed-9.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/09\/02\/consumo-de-probioticos-na-gestacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bebechegou.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Consumo de probi\u00f3ticos na gesta\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.bebechegou.com\/blog\/#website","url":"https:\/\/www.bebechegou.com\/blog\/","name":"bebechegou.com - Ch\u00e1 de beb\u00ea Online, Ch\u00e1 de Fraldas Online","description":"","publisher":{"@id":"https:\/\/www.bebechegou.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bebechegou.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.bebechegou.com\/blog\/#organization","name":"beb\u00ea chegou","url":"https:\/\/www.bebechegou.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2019\/11\/logo_bebe215.png","contentUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2019\/11\/logo_bebe215.png","width":215,"height":49,"caption":"beb\u00ea chegou"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com.br\/bebechegou1","http:\/\/instagram.com\/bebechegouoficial"]},{"@type":"Person","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/person\/359cfe12ff86958446433b00d3dd6f9c","name":"bebechegou"}]}},"_links":{"self":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=256"}],"version-history":[{"count":2,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/256\/revisions"}],"predecessor-version":[{"id":259,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/256\/revisions\/259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/media\/257"}],"wp:attachment":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}