{"id":364,"date":"2020-12-07T15:00:00","date_gmt":"2020-12-07T18:00:00","guid":{"rendered":"https:\/\/www.bebechegou.com\/blog\/?p=364"},"modified":"2020-12-07T14:50:26","modified_gmt":"2020-12-07T17:50:26","slug":"sexualidade-na-adolescencia","status":"publish","type":"post","link":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/","title":{"rendered":"Sexualidade na Adolesc\u00eancia"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4-1024x1024.png\" alt=\"\" data-id=\"365\" data-full-url=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png\" data-link=\"https:\/\/www.bebechegou.com\/blog\/?attachment_id=365\" class=\"wp-image-365 lazyload\" data-srcset=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4-1024x1024.png 1024w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4-300x300.png 300w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4-150x150.png 150w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4-768x768.png 768w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4-270x270.png 270w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Ol\u00e1, mam\u00e3es e papais!<\/p>\n\n\n\n<p>Hoje o texto ser\u00e1 direcionado para aqueles que possuem os filhos no per\u00edodo da adolesc\u00eancia. Precisamos entender primeiramente, qual fase \u00e9 essa e quais s\u00e3o suas caracter\u00edsticas: A adolesc\u00eancia \u00e9 um per\u00edodo que compreende indiv\u00edduos entre 10 e 19 anos de idade (OMS), e \u00e9<br>caracterizada por profundas transforma\u00e7\u00f5es f\u00edsicas e psicossociais, pelo despertar da sexualidade e separa\u00e7\u00e3o simb\u00f3lica dos pais.<\/p>\n\n\n\n<p>Os sentimentos de invulnerabilidade, pensamento m\u00e1gico e atitudes contestadoras s\u00e3o algumas das caracter\u00edsticas que dificultam a utiliza\u00e7\u00e3o efetiva de m\u00e9todos anticonceptivos, especialmente dos preservativos, fato que se contrap\u00f5e \u00e0s recomenda\u00e7\u00f5es sobre as pr\u00e1ticas sexuais protegidas.<\/p>\n\n\n\n<p>A literatura especializada aponta uma lacuna entre o conhecimento sobre os riscos das pr\u00e1ticas sexuais desprotegidas e o comportamento dos jovens que, mesmo sabendo das poss\u00edveis consequ\u00eancias, continuam a se expor.<\/p>\n\n\n\n<p>Trago para voc\u00eas a terceira edi\u00e7\u00e3o da Pesquisa Nacional de Sa\u00fade do Escolar &#8211; PeNSE, realizada em 2015 pelo Instituto Brasileiro de Geografia e Estat\u00edstica, IBGE, em parceria com o Minist\u00e9rio da Sa\u00fade e apoio do Minist\u00e9rio da Educa\u00e7\u00e3o, para mostrar os seguintes dados em rela\u00e7\u00e3o \u00e0<br>Sa\u00fade sexual e reprodutiva:<\/p>\n\n\n\n<p>1) Inicia\u00e7\u00e3o sexual: 27,5% dos escolares brasileiros do 9\u00ba ano do ensino fundamental j\u00e1 tiveram rela\u00e7\u00e3o sexual alguma vez. Dentre esses, 36,0% eram do g\u00eanero masculino, enquanto no g\u00eanero feminino esse percentual foi de 19,5%.<\/p>\n\n\n\n<p>2) Uso de preservativo: dentre os 27,5% de escolares que tiveram rela\u00e7\u00e3o sexual alguma vez na vida, 61,2% afirmaram ter usado preservativo na primeira rela\u00e7\u00e3o. Nos escolares do sexo masculino, esse percentual foi de 56,8% e entre os do sexo feminino, 68,7%. Quanto \u00e0 \u00faltima rela\u00e7\u00e3o sexual, 66,2% dos escolares sexualmente ativos responderam ter feito uso de<br>preservativo.<\/p>\n\n\n\n<p>3) Acesso a informa\u00e7\u00f5es sobre sexualidade na escola: 87,3% dos escolares do 9\u00ba ano do ensino fundamental receberam conhecimentos sobre infec\u00e7\u00f5es sexualmente transmiss\u00edveis (IST) e AIDS, sendo pouco mais frequente entre as meninas (88,4%) que entre meninos (86,2%).<\/p>\n\n\n\n<p>As infec\u00e7\u00f5es sexualmente transmiss\u00edveis (IST) s\u00e3o causadas por v\u00edrus, bact\u00e9rias ou outros microrganismos, transmitidos principalmente por contato sexual (vaginal, anal e\/ou oral) sem o uso de preservativo masculino ou feminino, com uma pessoa que esteja infectada. <\/p>\n\n\n\n<p>A transmiss\u00e3o pode acontecer tamb\u00e9m de m\u00e3e para filho durante a gesta\u00e7\u00e3o, o parto ou a amamenta\u00e7\u00e3o (transmiss\u00e3o vertical), e pela utiliza\u00e7\u00e3o de seringas, agulhas ou outro material p\u00e9rfuro cortante partilhado.<\/p>\n\n\n\n<p>As IST s\u00e3o consideradas como um dos problemas de sa\u00fade p\u00fablica mais comuns em todo o mundo. Os infectados s\u00e3o mais vulner\u00e1veis \u00e0 associa\u00e7\u00e3o de mais de uma IST e existe rela\u00e7\u00e3o com o aumento da mortalidade materna e infantil. <\/p>\n\n\n\n<p>A Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) estima em mais de 1 milh\u00e3o de casos novos de IST por dia no mundo. Ao ano, ocorrem cerca de 357 milh\u00f5es de novas infec\u00e7\u00f5es, entre clam\u00eddia, gonorreia, s\u00edfilis e tricomon\u00edase. <\/p>\n\n\n\n<p>A presen\u00e7a de uma IST, como s\u00edfilis ou gonorreia, aumenta consideravelmente o risco de se adquirir ou transmitir a infec\u00e7\u00e3o por V\u00edrus da Imunodefici\u00eancia Humana (HIV). Em especial, a s\u00edfilis na gesta\u00e7\u00e3o leva a mais de 300 mil mortes fetais e neonatais por ano no mundo, e coloca um<br>adicional de 215 mil crian\u00e7as com maior risco de morte prematura.<\/p>\n\n\n\n<p>Por isso, informa\u00e7\u00e3o \u00e9 essencial. Voc\u00ea conversa com seu filho sobre essa tem\u00e1tica? \u00c9 importante lembrar que o fato de conversar e debater esse tema n\u00e3o \u00e9 uma forma de incentivar a sexualidade precoce e sim, informar e proteger o pr\u00f3prio adolescente.<\/p>\n\n\n\n<p>Um beijo, Dra Beatriz Rom\u00e3o Amatto \u2013 CRM 181.573 \/ RQE 82.740 \u2013 M\u00e9dica Pediatra \/ Instagram@drabeatrizamatto<br> Fonte: Sociedade Brasileira de Pediatria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, mam\u00e3es e papais! Hoje o texto ser\u00e1 direcionado para aqueles que possuem os filhos no per\u00edodo da adolesc\u00eancia. Precisamos entender primeiramente, qual fase \u00e9 essa e quais s\u00e3o suas caracter\u00edsticas: A adolesc\u00eancia \u00e9 um per\u00edodo que compreende indiv\u00edduos entre 10 e 19 anos de idade (OMS), e \u00e9caracterizada por profundas transforma\u00e7\u00f5es f\u00edsicas e psicossociais, &hellip; <\/p>\n<p class=\"read-more\"><a class=\"readmore-btn\" href=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/\">+<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":365,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238],"tags":[265,119,75,266],"class_list":["post-364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-criancas","tag-adolescencia","tag-filhos","tag-maternidade","tag-pre-adolescentes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sexualidade na Adolesc\u00eancia - Blog - bebechegou.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sexualidade na Adolesc\u00eancia - Blog - bebechegou.com\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, mam\u00e3es e papais! Hoje o texto ser\u00e1 direcionado para aqueles que possuem os filhos no per\u00edodo da adolesc\u00eancia. Precisamos entender primeiramente, qual fase \u00e9 essa e quais s\u00e3o suas caracter\u00edsticas: A adolesc\u00eancia \u00e9 um per\u00edodo que compreende indiv\u00edduos entre 10 e 19 anos de idade (OMS), e \u00e9caracterizada por profundas transforma\u00e7\u00f5es f\u00edsicas e psicossociais, &hellip; + Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - bebechegou.com\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com.br\/bebechegou1\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-07T18:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"bebechegou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bebechegou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/\"},\"author\":{\"name\":\"bebechegou\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/person\\\/359cfe12ff86958446433b00d3dd6f9c\"},\"headline\":\"Sexualidade na Adolesc\u00eancia\",\"datePublished\":\"2020-12-07T18:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/\"},\"wordCount\":632,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png\",\"keywords\":[\"adolescencia\",\"filhos\",\"maternidade\",\"pre adolescentes\"],\"articleSection\":[\"Crian\u00e7as\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/\",\"name\":\"Sexualidade na Adolesc\u00eancia - Blog - bebechegou.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png\",\"datePublished\":\"2020-12-07T18:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png\",\"contentUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/12\\\/07\\\/sexualidade-na-adolescencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sexualidade na Adolesc\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\",\"name\":\"bebechegou.com - Ch\u00e1 de beb\u00ea Online, Ch\u00e1 de Fraldas Online\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\",\"name\":\"beb\u00ea chegou\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_bebe215.png\",\"contentUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_bebe215.png\",\"width\":215,\"height\":49,\"caption\":\"beb\u00ea chegou\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com.br\\\/bebechegou1\",\"http:\\\/\\\/instagram.com\\\/bebechegouoficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/person\\\/359cfe12ff86958446433b00d3dd6f9c\",\"name\":\"bebechegou\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sexualidade na Adolesc\u00eancia - Blog - bebechegou.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/","og_locale":"pt_BR","og_type":"article","og_title":"Sexualidade na Adolesc\u00eancia - Blog - bebechegou.com","og_description":"Ol\u00e1, mam\u00e3es e papais! Hoje o texto ser\u00e1 direcionado para aqueles que possuem os filhos no per\u00edodo da adolesc\u00eancia. Precisamos entender primeiramente, qual fase \u00e9 essa e quais s\u00e3o suas caracter\u00edsticas: A adolesc\u00eancia \u00e9 um per\u00edodo que compreende indiv\u00edduos entre 10 e 19 anos de idade (OMS), e \u00e9caracterizada por profundas transforma\u00e7\u00f5es f\u00edsicas e psicossociais, &hellip; + Read More","og_url":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/","og_site_name":"Blog - bebechegou.com","article_publisher":"http:\/\/facebook.com.br\/bebechegou1","article_published_time":"2020-12-07T18:00:00+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png","type":"image\/png"}],"author":"bebechegou","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"bebechegou","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/#article","isPartOf":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/"},"author":{"name":"bebechegou","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/person\/359cfe12ff86958446433b00d3dd6f9c"},"headline":"Sexualidade na Adolesc\u00eancia","datePublished":"2020-12-07T18:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/"},"wordCount":632,"publisher":{"@id":"https:\/\/www.bebechegou.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png","keywords":["adolescencia","filhos","maternidade","pre adolescentes"],"articleSection":["Crian\u00e7as"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/","url":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/","name":"Sexualidade na Adolesc\u00eancia - Blog - bebechegou.com","isPartOf":{"@id":"https:\/\/www.bebechegou.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/#primaryimage"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png","datePublished":"2020-12-07T18:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/#primaryimage","url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png","contentUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/12\/C\u00c3\u00b3pia-de-e-chegou-feed-4.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/12\/07\/sexualidade-na-adolescencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bebechegou.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Sexualidade na Adolesc\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/www.bebechegou.com\/blog\/#website","url":"https:\/\/www.bebechegou.com\/blog\/","name":"bebechegou.com - Ch\u00e1 de beb\u00ea Online, Ch\u00e1 de Fraldas Online","description":"","publisher":{"@id":"https:\/\/www.bebechegou.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bebechegou.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.bebechegou.com\/blog\/#organization","name":"beb\u00ea chegou","url":"https:\/\/www.bebechegou.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2019\/11\/logo_bebe215.png","contentUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2019\/11\/logo_bebe215.png","width":215,"height":49,"caption":"beb\u00ea chegou"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com.br\/bebechegou1","http:\/\/instagram.com\/bebechegouoficial"]},{"@type":"Person","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/person\/359cfe12ff86958446433b00d3dd6f9c","name":"bebechegou"}]}},"_links":{"self":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=364"}],"version-history":[{"count":1,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/364\/revisions"}],"predecessor-version":[{"id":366,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/364\/revisions\/366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/media\/365"}],"wp:attachment":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}