{"id":385,"date":"2021-01-11T10:30:00","date_gmt":"2021-01-11T13:30:00","guid":{"rendered":"https:\/\/www.bebechegou.com\/blog\/?p=385"},"modified":"2021-01-08T09:07:13","modified_gmt":"2021-01-08T12:07:13","slug":"reacoes-alergicas-a-insetos","status":"publish","type":"post","link":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/","title":{"rendered":"Rea\u00e7\u00f5es al\u00e9rgicas a insetos"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-src=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6-1024x1024.png\" alt=\"\" class=\"wp-image-386 lazyload\" data-srcset=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6-1024x1024.png 1024w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6-300x300.png 300w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6-150x150.png 150w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6-768x768.png 768w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6-270x270.png 270w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><\/figure>\n\n\n\n<p>Ol\u00e1, mam\u00e3es e papais! Mais um ano se inicia, e com ele, o ver\u00e3o, sol, calor \u2013 e insetos \u2013 tamb\u00e9m. Separei ent\u00e3o algumas dicas relacionadas \u00e0 rea\u00e7\u00f5es al\u00e9rgicas nas crian\u00e7as secund\u00e1rias \u00e0 picada de insetos. <\/p>\n\n\n\n<p>Inicialmente, precisamos entender que QUALQUER \u00a0inseto que pique poder\u00e1 provocar rea\u00e7\u00e3o nas crian\u00e7as suscet\u00edveis. Entre os mais comuns, est\u00e3o os mosquitos, pulgas e carrapatos. <\/p>\n\n\n\n<p>Essa rea\u00e7\u00e3o al\u00e9rgica tem um nome: chama-se prurigo estr\u00f3fulo ou urtic\u00e1ria papular.<\/p>\n\n\n\n<p>Raramente essas rea\u00e7\u00f5es ter\u00e3o inicio antes do sexto m\u00eas de vida, pois para que ocorra a sensibiliza\u00e7\u00e3o al\u00e9rgica, s\u00e3o necess\u00e1rias diversas picadas. O tempo para o desenvolvimento da alergia varia de crian\u00e7a para crian\u00e7a e depende do n\u00famero de exposi\u00e7\u00f5es aos insetos no seu dia a dia. <\/p>\n\n\n\n<p>Ap\u00f3s ter sido sensibilizada, a crian\u00e7a apresentar\u00e1 a rea\u00e7\u00e3o. A doen\u00e7a, na maioria das vezes, tem in\u00edcio entre os 12 e os 24 meses de vida. A tend\u00eancia \u00e9 melhorar apenas \u00a0por volta dos 10 anos de idade.<\/p>\n\n\n\n<p> Conseguimos reconhecer as les\u00f5es atrav\u00e9s da presen\u00e7a de p\u00e1pulas (bolinhas) vermelhas e\/ou ves\u00edculas (bolhas de \u00e1gua) de distribui\u00e7\u00e3o em \u201clinhas\u201d ou aos pares, com coceira. Os mosquitos e pernilongos geralmente picam nas regi\u00f5es expostas do corpo, como bra\u00e7os e pernas. <\/p>\n\n\n\n<p>O tronco \u00e9 acometido principalmente quando os agentes s\u00e3o \u201cinsetos andadores\u201d como pulgas ou percevejos. As les\u00f5es podem surgir agudamente ou alguns dias ap\u00f3s as picadas, e a rea\u00e7\u00e3o pode durar algumas semanas quando n\u00e3o tratadas. <\/p>\n\n\n\n<p>Ao final, pode ficar uma mancha escurecida que demora meses para desaparecer.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dicas<\/h2>\n\n\n\n<p>Existem algumas dicas que podem evitar o surgimento do prurigo estr\u00f3fulo, sendo elas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li> Usar roupas de mangas longas, cal\u00e7as compridas e meias de prefer\u00eancia por cima da cal\u00e7a para fazer uma barreira f\u00edsica; <\/li><li> Somente abrir as janelas e portas ap\u00f3s o nascer do sol, fechando-as antes do p\u00f4r do sol (hor\u00e1rio que os insetos procuram a \u201crefei\u00e7\u00e3o\u201d); <\/li><li> Instalar telas nas janelas e portas da casa; <\/li><li>Utilizar mosquiteiros nas camas e ber\u00e7os;<\/li><li>Aplicar produtos \u00e0 base de permetrina nas telas, mosqueteiros e cortinas;<\/li><li>Fazer uso do repelente t\u00f3pico durante o dia se a crian\u00e7a for exposta aos insetos;<\/li><li>Preferir o uso, se poss\u00edvel, de ar condicionado, pois ambientes climatizados afastam os mosquitos;<\/li><li>Dedetizar periodicamente a casa;<\/li><li>Usar repelentes el\u00e9tricos;<\/li><li> Manter limpo o terreno da casa, al\u00e9m de retirar sempre o lixo e entulhos que possam acumular \u00e1gua parada e servirem como criadouros de insetos voadores; <\/li><li>Eliminar as pulgas dos animais de estima\u00e7\u00e3o. <\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Repelentes<\/h2>\n\n\n\n<p>Uma d\u00favida comum gira em torno do uso de repelentes. Os repelentes t\u00f3picos podem ser usados durante passeios em locais com maior n\u00famero de insetos como praias, parques, fazendas e ch\u00e1caras. N\u00e3o devem ser aplicados durante o sono ou por per\u00edodos prolongados. <\/p>\n\n\n\n<p>A idade de uso deve ser checada no r\u00f3tulo, alguns produtos podem ser utilizados eventualmente a partir de 3 meses e s\u00e3o recomendados de forma mais segura a partir de 6 meses de vida.<\/p>\n\n\n\n<p>Quanto \u00e0 aplica\u00e7\u00e3o dos repelentes, algumas orienta\u00e7\u00f5es:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>NUNCA aplicar na m\u00e3o da crian\u00e7a para que ela mesma espalhe no corpo. Elas podem esfregar os olhos ou mesmo colocar a m\u00e3o na boca;<\/li><li> Aplicar a quantidade e intervalo recomendados pelo fabricante no r\u00f3tulo do produto; <\/li><li> N\u00c3O aplicar no rosto ou sobre a pele traumatizada; <\/li><li>Assim que n\u00e3o for mais necess\u00e1rio o repelente deve ser removido com um banho com \u00e1gua e sabonete;<\/li><li>N\u00c3O permitir que a crian\u00e7a durma com o repelente aplicado;<\/li><li>Produtos em associa\u00e7\u00e3o do tipo repelente com hidratante ou repelente com protetor solar devem ser evitados.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">E o que vem primeiro, protetor solar ou repelente?<\/h2>\n\n\n\n<p>Recomenda-se aplicar primeiro o protetor solar e ap\u00f3s secar, realizar a aplica\u00e7\u00e3o do repelente escolhido.<\/p>\n\n\n\n<p>Quando as les\u00f5es estiverem presentes, o tratamento deve ser orientado pelo pediatra ou dermatopediatra, mas geralmente consiste de pomada anti-inflamat\u00f3ria e anti-histam\u00ednicos orais.<\/p>\n\n\n\n<p>Voc\u00ea j\u00e1 conhecia essas dicas? <\/p>\n\n\n\n<p>FONTE: SBP \u2013 Pediatria para Fam\u00edlias. <br>Um beijo, Dra Beatriz Rom\u00e3o Amatto \u2013 M\u00e9dica Pediatra \u2013 CRM 181.573 \/RQE 82.740 \u2013 Instagram @drabeatrizamatto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, mam\u00e3es e papais! Mais um ano se inicia, e com ele, o ver\u00e3o, sol, calor \u2013 e insetos \u2013 tamb\u00e9m. Separei ent\u00e3o algumas dicas relacionadas \u00e0 rea\u00e7\u00f5es al\u00e9rgicas nas crian\u00e7as secund\u00e1rias \u00e0 picada de insetos. Inicialmente, precisamos entender que QUALQUER \u00a0inseto que pique poder\u00e1 provocar rea\u00e7\u00e3o nas crian\u00e7as suscet\u00edveis. Entre os mais comuns, est\u00e3o &hellip; <\/p>\n<p class=\"read-more\"><a class=\"readmore-btn\" href=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/\">+<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":386,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238],"tags":[286,287,90,288,84,282,36,20,87,75,6,283,281,285,284],"class_list":["post-385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-criancas","tag-alergias","tag-bebe-com-alergia","tag-bebes","tag-crianca-com-alergia","tag-estou-gravida","tag-ferias-2021","tag-gestantes","tag-gravidas","tag-mamae-de-primeira-viagem","tag-maternidade","tag-pais-de-primeira-viagem","tag-picadas-de-insetos-em-criancas","tag-verao-2021","tag-viagem-com-bebe","tag-viagem-com-crianca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rea\u00e7\u00f5es al\u00e9rgicas a insetos - Blog - bebechegou.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rea\u00e7\u00f5es al\u00e9rgicas a insetos - Blog - bebechegou.com\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, mam\u00e3es e papais! Mais um ano se inicia, e com ele, o ver\u00e3o, sol, calor \u2013 e insetos \u2013 tamb\u00e9m. Separei ent\u00e3o algumas dicas relacionadas \u00e0 rea\u00e7\u00f5es al\u00e9rgicas nas crian\u00e7as secund\u00e1rias \u00e0 picada de insetos. Inicialmente, precisamos entender que QUALQUER \u00a0inseto que pique poder\u00e1 provocar rea\u00e7\u00e3o nas crian\u00e7as suscet\u00edveis. Entre os mais comuns, est\u00e3o &hellip; + Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - bebechegou.com\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com.br\/bebechegou1\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-11T13:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"bebechegou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bebechegou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/\"},\"author\":{\"name\":\"bebechegou\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/person\\\/359cfe12ff86958446433b00d3dd6f9c\"},\"headline\":\"Rea\u00e7\u00f5es al\u00e9rgicas a insetos\",\"datePublished\":\"2021-01-11T13:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/\"},\"wordCount\":724,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png\",\"keywords\":[\"alergias\",\"beb\u00ea com alergia\",\"beb\u00eas\",\"crian\u00e7a com alergia\",\"estou gravida\",\"f\u00e9rias 2021\",\"gestantes\",\"gr\u00e1vidas\",\"mamae de primeira viagem\",\"maternidade\",\"pais de primeira viagem\",\"picadas de insetos em crian\u00e7as\",\"verao 2021\",\"viagem com beb\u00ea\",\"viagem com crian\u00e7a\"],\"articleSection\":[\"Crian\u00e7as\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/\",\"name\":\"Rea\u00e7\u00f5es al\u00e9rgicas a insetos - Blog - bebechegou.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png\",\"datePublished\":\"2021-01-11T13:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png\",\"contentUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2021\\\/01\\\/11\\\/reacoes-alergicas-a-insetos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rea\u00e7\u00f5es al\u00e9rgicas a insetos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\",\"name\":\"bebechegou.com - Ch\u00e1 de beb\u00ea Online, Ch\u00e1 de Fraldas Online\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\",\"name\":\"beb\u00ea chegou\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_bebe215.png\",\"contentUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_bebe215.png\",\"width\":215,\"height\":49,\"caption\":\"beb\u00ea chegou\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com.br\\\/bebechegou1\",\"http:\\\/\\\/instagram.com\\\/bebechegouoficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/person\\\/359cfe12ff86958446433b00d3dd6f9c\",\"name\":\"bebechegou\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rea\u00e7\u00f5es al\u00e9rgicas a insetos - Blog - bebechegou.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/","og_locale":"pt_BR","og_type":"article","og_title":"Rea\u00e7\u00f5es al\u00e9rgicas a insetos - Blog - bebechegou.com","og_description":"Ol\u00e1, mam\u00e3es e papais! Mais um ano se inicia, e com ele, o ver\u00e3o, sol, calor \u2013 e insetos \u2013 tamb\u00e9m. Separei ent\u00e3o algumas dicas relacionadas \u00e0 rea\u00e7\u00f5es al\u00e9rgicas nas crian\u00e7as secund\u00e1rias \u00e0 picada de insetos. Inicialmente, precisamos entender que QUALQUER \u00a0inseto que pique poder\u00e1 provocar rea\u00e7\u00e3o nas crian\u00e7as suscet\u00edveis. Entre os mais comuns, est\u00e3o &hellip; + Read More","og_url":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/","og_site_name":"Blog - bebechegou.com","article_publisher":"http:\/\/facebook.com.br\/bebechegou1","article_published_time":"2021-01-11T13:30:00+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png","type":"image\/png"}],"author":"bebechegou","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"bebechegou","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/#article","isPartOf":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/"},"author":{"name":"bebechegou","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/person\/359cfe12ff86958446433b00d3dd6f9c"},"headline":"Rea\u00e7\u00f5es al\u00e9rgicas a insetos","datePublished":"2021-01-11T13:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/"},"wordCount":724,"publisher":{"@id":"https:\/\/www.bebechegou.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png","keywords":["alergias","beb\u00ea com alergia","beb\u00eas","crian\u00e7a com alergia","estou gravida","f\u00e9rias 2021","gestantes","gr\u00e1vidas","mamae de primeira viagem","maternidade","pais de primeira viagem","picadas de insetos em crian\u00e7as","verao 2021","viagem com beb\u00ea","viagem com crian\u00e7a"],"articleSection":["Crian\u00e7as"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/","url":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/","name":"Rea\u00e7\u00f5es al\u00e9rgicas a insetos - Blog - bebechegou.com","isPartOf":{"@id":"https:\/\/www.bebechegou.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/#primaryimage"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png","datePublished":"2021-01-11T13:30:00+00:00","breadcrumb":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/#primaryimage","url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png","contentUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2021\/01\/C\u00c3\u00b3pia-de-e-chegou-feed-6.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2021\/01\/11\/reacoes-alergicas-a-insetos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bebechegou.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Rea\u00e7\u00f5es al\u00e9rgicas a insetos"}]},{"@type":"WebSite","@id":"https:\/\/www.bebechegou.com\/blog\/#website","url":"https:\/\/www.bebechegou.com\/blog\/","name":"bebechegou.com - Ch\u00e1 de beb\u00ea Online, Ch\u00e1 de Fraldas Online","description":"","publisher":{"@id":"https:\/\/www.bebechegou.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bebechegou.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.bebechegou.com\/blog\/#organization","name":"beb\u00ea chegou","url":"https:\/\/www.bebechegou.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2019\/11\/logo_bebe215.png","contentUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2019\/11\/logo_bebe215.png","width":215,"height":49,"caption":"beb\u00ea chegou"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com.br\/bebechegou1","http:\/\/instagram.com\/bebechegouoficial"]},{"@type":"Person","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/person\/359cfe12ff86958446433b00d3dd6f9c","name":"bebechegou"}]}},"_links":{"self":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=385"}],"version-history":[{"count":1,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/385\/revisions"}],"predecessor-version":[{"id":387,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/385\/revisions\/387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/media\/386"}],"wp:attachment":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}