{"id":98,"date":"2020-05-25T15:28:40","date_gmt":"2020-05-25T18:28:40","guid":{"rendered":"https:\/\/www.bebechegou.com\/blog\/?p=98"},"modified":"2020-05-25T15:28:42","modified_gmt":"2020-05-25T18:28:42","slug":"como-aumentar-a-imunidade-das-criancas","status":"publish","type":"post","link":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/","title":{"rendered":"Como aumentar a imunidade das crian\u00e7as?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"2560\" height=\"1810\" data-src=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/05\/714-scaled.jpg\" alt=\"\" class=\"wp-image-99 lazyload\" data-srcset=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/05\/714-scaled.jpg 2560w, https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/05\/714-300x212.jpg 300w\" data-sizes=\"(max-width: 2560px) 100vw, 2560px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/1810;\" \/><\/figure>\n\n\n\n<p>Ol\u00e1,\nmam\u00e3es e papais! <\/p>\n\n\n\n<p>Sabemos\nque o sistema imunol\u00f3gico das crian\u00e7as come\u00e7a a ser criado ainda durante a gesta\u00e7\u00e3o\nmaterna, e que ter\u00e1 seu total desenvolvimento apenas durante a adolesc\u00eancia.\nNesta grande janela de tempo, \u00e9&nbsp; comum\nque as crian\u00e7as apresentem as infec\u00e7\u00f5es de repeti\u00e7\u00e3o, muito mais frequentes nos\nprimeiros 5 anos de vida e com melhora progressiva \u00e0 medida que crescem. <\/p>\n\n\n\n<p>Dados\ndo Minist\u00e9rio da Sa\u00fade sugerem que o pico de interna\u00e7\u00f5es hospitalares\nsecund\u00e1rias a infec\u00e7\u00f5es respirat\u00f3rias ocorre entre o in\u00edcio de abril e final de\njulho (per\u00edodo do outono e inverno), em decorr\u00eancia da sazonalidade de alguns\ndos principais v\u00edrus respirat\u00f3rios (por exemplo, o Influenza e o V\u00edrus\nSincicial Respirat\u00f3rio) e devido \u00e0 tend\u00eancia de em \u00e9pocas mais frias as pessoas\nse aglomerarem mais. <\/p>\n\n\n\n<p>Voc\u00ea sabia, tamb\u00e9m, \u00a0que \u00e9 esperado que crian\u00e7as pequenas apresentem uma m\u00e9dia de 8-10 epis\u00f3dios de infec\u00e7\u00f5es de vias a\u00e9reas superiores e inferiores anualmente? Esses dados assustam, e por isso \u00e9 muito frequente nas consultas pedi\u00e1tricas a solicita\u00e7\u00e3o pelos familiares de \u201cmedicamentos m\u00e1gicos\u201d que aumentem a imunidade das crian\u00e7as. Entretanto, sabemos que at\u00e9 o momento, ele n\u00e3o existe, e que devemos nos esfor\u00e7ar para manter alguns cuidados e h\u00e1bitos saud\u00e1veis no dia-a-dia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trago ent\u00e3o algumas dicas. \u00a0Vamos l\u00e1?<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li> Amamente! Durante o aleitamento materno, o beb\u00ea recebe anticorpos produzidos pela m\u00e3e. Esses anticorpos s\u00e3o capazes de combater infec\u00e7\u00f5es caso o beb\u00ea tenha exposi\u00e7\u00e3o a elas. Al\u00e9m disso, o contato com os microorganismos existentes na\u00a0 pele da m\u00e3e e que entram atrav\u00e9s da boca\u00a0 do beb\u00ea tamb\u00e9m favorece a coloniza\u00e7\u00e3o da microbiota intestinal.<\/li><li> Forne\u00e7a uma alimenta\u00e7\u00e3o saud\u00e1vel! Os diversos nutrientes presentes nos alimentos saud\u00e1veis (dos minerais \u00e0s vitaminas) participam dos processos antioxidantes que protegem as c\u00e9lulas de infec\u00e7\u00f5es. Idealmente, forne\u00e7a uma por\u00e7\u00e3o de cada grupo alimentar em cada refei\u00e7\u00e3o. Varie! Ningu\u00e9m gosta de monotonia (principalmente as crian\u00e7as).  <\/li><li>Vacine! As vacinas s\u00e3o a maneira mais segura e eficaz de tornar o organismo imune a diversas doen\u00e7as. O organismo produz anticorpos espec\u00edficos contra o agressor sem ficar doente. Assim, caso a crian\u00e7a tenha contato com os invasores, ele ativar\u00e1 a mem\u00f3ria imunol\u00f3gica e combater\u00e1 a infec\u00e7\u00e3o.<\/li><li> Incentive a atividade f\u00edsica: ela aumenta o apetite, melhora o sono e favorece condi\u00e7\u00f5es respirat\u00f3rias. Lembre que a atividade deve ser adequada para cada faixa et\u00e1ria. Pergunte \u00e0 crian\u00e7a suas prefer\u00eancias, caso contr\u00e1rio, as chances de desist\u00eancia s\u00e3o grandes. <\/li><li> Bem-estar: evitar o estresse \u00e9 fundamental. Sim, n\u00e3o s\u00e3o somente os adultos que sofrem com esse mau. Nas crian\u00e7as, chamamos de estresse t\u00f3xico. Ele libera subst\u00e2ncias (como por exemplo o horm\u00f4nio cortisol) que em excesso no organismo, afetam o sistema imunol\u00f3gico. Evitar o exagero de atividades extracurriculares e investir em pr\u00e1ticas e brincadeiras que ajudem a relaxar. <\/li><li>\u201cVitamina S: s de sujeira\u201d: evite criar o seu filho\/a em uma bolha! Brincar com terra, por exemplo \u00e9 saud\u00e1vel! O organismo \u00e9 capaz de produzir anticorpos nestas situa\u00e7\u00f5es! Obviamente, a higiene deve ser garantida, por\u00e9m, o excesso de limpeza (a famosa \u201cneura\u201d) pode ser prejudicial.<\/li><li>Cuidado com os Antibi\u00f3ticos: a medica\u00e7\u00e3o \u201cmata\u201d tanto os microorganismos ruins quanto os bons, levando a uma desorganiza\u00e7\u00e3o da flora intestinal. Devem ser prescritos pelo m\u00e9dico se houver indica\u00e7\u00e3o: N\u00c3O automedique seu filho! Al\u00e9m disso, o uso indiscriminado de antibi\u00f3ticos podem levar \u00e0 uma resist\u00eancia bacteriana.<\/li><\/ul>\n\n\n\n<p><br>Ah, e para relembrar: Os bons h\u00e1bitos substituem qualquer rem\u00e9dio!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Texto: Dra. Beatriz Rom\u00e3o Amatto \u2013 M\u00e9dica Pediatra, Consultora do Sono Infantil, Instrutora de Shantala, P\u00f3s Graduada em Emerg\u00eancias Pedi\u00e1tricas . CRM 181.573 \/ RQUE 82.740 \u2013 Instagram @drabeatrizamatto<\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, mam\u00e3es e papais! Sabemos que o sistema imunol\u00f3gico das crian\u00e7as come\u00e7a a ser criado ainda durante a gesta\u00e7\u00e3o materna, e que ter\u00e1 seu total desenvolvimento apenas durante a adolesc\u00eancia. Nesta grande janela de tempo, \u00e9&nbsp; comum que as crian\u00e7as apresentem as infec\u00e7\u00f5es de repeti\u00e7\u00e3o, muito mais frequentes nos primeiros 5 anos de vida e &hellip; <\/p>\n<p class=\"read-more\"><a class=\"readmore-btn\" href=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/\">+<span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":99,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[27,29,28,32,31,30],"class_list":["post-98","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuidados-com-o-bebe","tag-cuidados-com-o-bebe","tag-imunidade-bebe","tag-imunidade-crianca","tag-maes-de-primeira-viagem","tag-pediatria","tag-saude-do-bebe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como aumentar a imunidade das crian\u00e7as? - Blog - bebechegou.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como aumentar a imunidade das crian\u00e7as? - Blog - bebechegou.com\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, mam\u00e3es e papais! Sabemos que o sistema imunol\u00f3gico das crian\u00e7as come\u00e7a a ser criado ainda durante a gesta\u00e7\u00e3o materna, e que ter\u00e1 seu total desenvolvimento apenas durante a adolesc\u00eancia. Nesta grande janela de tempo, \u00e9&nbsp; comum que as crian\u00e7as apresentem as infec\u00e7\u00f5es de repeti\u00e7\u00e3o, muito mais frequentes nos primeiros 5 anos de vida e &hellip; + Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - bebechegou.com\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com.br\/bebechegou1\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T18:28:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-25T18:28:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/05\/714-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bebechegou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bebechegou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/\"},\"author\":{\"name\":\"bebechegou\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/person\\\/359cfe12ff86958446433b00d3dd6f9c\"},\"headline\":\"Como aumentar a imunidade das crian\u00e7as?\",\"datePublished\":\"2020-05-25T18:28:40+00:00\",\"dateModified\":\"2020-05-25T18:28:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/\"},\"wordCount\":668,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/714-scaled.jpg\",\"keywords\":[\"cuidados com o beb\u00ea\",\"imunidade beb\u00ea\",\"imunidade crian\u00e7a\",\"m\u00e3es de primeira viagem\",\"pediatria\",\"sa\u00fade do beb\u00ea\"],\"articleSection\":[\"Cuidados com o Beb\u00ea\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/\",\"name\":\"Como aumentar a imunidade das crian\u00e7as? - Blog - bebechegou.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/714-scaled.jpg\",\"datePublished\":\"2020-05-25T18:28:40+00:00\",\"dateModified\":\"2020-05-25T18:28:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/714-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/714-scaled.jpg\",\"width\":2560,\"height\":1810,\"caption\":\"kids immune protection system vector illustration\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/index.php\\\/2020\\\/05\\\/25\\\/como-aumentar-a-imunidade-das-criancas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como aumentar a imunidade das crian\u00e7as?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\",\"name\":\"bebechegou.com - Ch\u00e1 de beb\u00ea Online, Ch\u00e1 de Fraldas Online\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#organization\",\"name\":\"beb\u00ea chegou\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_bebe215.png\",\"contentUrl\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_bebe215.png\",\"width\":215,\"height\":49,\"caption\":\"beb\u00ea chegou\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com.br\\\/bebechegou1\",\"http:\\\/\\\/instagram.com\\\/bebechegouoficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bebechegou.com\\\/blog\\\/#\\\/schema\\\/person\\\/359cfe12ff86958446433b00d3dd6f9c\",\"name\":\"bebechegou\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como aumentar a imunidade das crian\u00e7as? - Blog - bebechegou.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/","og_locale":"pt_BR","og_type":"article","og_title":"Como aumentar a imunidade das crian\u00e7as? - Blog - bebechegou.com","og_description":"Ol\u00e1, mam\u00e3es e papais! Sabemos que o sistema imunol\u00f3gico das crian\u00e7as come\u00e7a a ser criado ainda durante a gesta\u00e7\u00e3o materna, e que ter\u00e1 seu total desenvolvimento apenas durante a adolesc\u00eancia. Nesta grande janela de tempo, \u00e9&nbsp; comum que as crian\u00e7as apresentem as infec\u00e7\u00f5es de repeti\u00e7\u00e3o, muito mais frequentes nos primeiros 5 anos de vida e &hellip; + Read More","og_url":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/","og_site_name":"Blog - bebechegou.com","article_publisher":"http:\/\/facebook.com.br\/bebechegou1","article_published_time":"2020-05-25T18:28:40+00:00","article_modified_time":"2020-05-25T18:28:42+00:00","og_image":[{"width":2560,"height":1810,"url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/05\/714-scaled.jpg","type":"image\/jpeg"}],"author":"bebechegou","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"bebechegou","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/#article","isPartOf":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/"},"author":{"name":"bebechegou","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/person\/359cfe12ff86958446433b00d3dd6f9c"},"headline":"Como aumentar a imunidade das crian\u00e7as?","datePublished":"2020-05-25T18:28:40+00:00","dateModified":"2020-05-25T18:28:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/"},"wordCount":668,"publisher":{"@id":"https:\/\/www.bebechegou.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/05\/714-scaled.jpg","keywords":["cuidados com o beb\u00ea","imunidade beb\u00ea","imunidade crian\u00e7a","m\u00e3es de primeira viagem","pediatria","sa\u00fade do beb\u00ea"],"articleSection":["Cuidados com o Beb\u00ea"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/","url":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/","name":"Como aumentar a imunidade das crian\u00e7as? - Blog - bebechegou.com","isPartOf":{"@id":"https:\/\/www.bebechegou.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/#primaryimage"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/05\/714-scaled.jpg","datePublished":"2020-05-25T18:28:40+00:00","dateModified":"2020-05-25T18:28:42+00:00","breadcrumb":{"@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/#primaryimage","url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/05\/714-scaled.jpg","contentUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2020\/05\/714-scaled.jpg","width":2560,"height":1810,"caption":"kids immune protection system vector illustration"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bebechegou.com\/blog\/index.php\/2020\/05\/25\/como-aumentar-a-imunidade-das-criancas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bebechegou.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Como aumentar a imunidade das crian\u00e7as?"}]},{"@type":"WebSite","@id":"https:\/\/www.bebechegou.com\/blog\/#website","url":"https:\/\/www.bebechegou.com\/blog\/","name":"bebechegou.com - Ch\u00e1 de beb\u00ea Online, Ch\u00e1 de Fraldas Online","description":"","publisher":{"@id":"https:\/\/www.bebechegou.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bebechegou.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.bebechegou.com\/blog\/#organization","name":"beb\u00ea chegou","url":"https:\/\/www.bebechegou.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2019\/11\/logo_bebe215.png","contentUrl":"https:\/\/www.bebechegou.com\/blog\/wp-content\/uploads\/2019\/11\/logo_bebe215.png","width":215,"height":49,"caption":"beb\u00ea chegou"},"image":{"@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com.br\/bebechegou1","http:\/\/instagram.com\/bebechegouoficial"]},{"@type":"Person","@id":"https:\/\/www.bebechegou.com\/blog\/#\/schema\/person\/359cfe12ff86958446433b00d3dd6f9c","name":"bebechegou"}]}},"_links":{"self":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":1,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/98\/revisions"}],"predecessor-version":[{"id":100,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/98\/revisions\/100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/media\/99"}],"wp:attachment":[{"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=98"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=98"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bebechegou.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}